{"id":1,"count":2,"description":"","link":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/","name":"Senza categoria","slug":"senza-categoria","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senza categoria Archivi - Residenza Casoro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senza categoria Archivi - Residenza Casoro\" \/>\n<meta property=\"og:url\" content=\"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Residenza Casoro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/residenza-casoro.ch\\\/en\\\/category\\\/senza-categoria\\\/\",\"url\":\"http:\\\/\\\/residenza-casoro.ch\\\/en\\\/category\\\/senza-categoria\\\/\",\"name\":\"Senza categoria Archivi - Residenza Casoro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/residenza-casoro.ch\\\/en\\\/category\\\/senza-categoria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/residenza-casoro.ch\\\/en\\\/category\\\/senza-categoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senza categoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/\",\"name\":\"Residenza Casoro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/#organization\",\"name\":\"Residenza Casoro\",\"url\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/residenza-casoro.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Residenza-Casoro-Icon.png\",\"contentUrl\":\"https:\\\/\\\/residenza-casoro.ch\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Residenza-Casoro-Icon.png\",\"width\":120,\"height\":120,\"caption\":\"Residenza Casoro\"},\"image\":{\"@id\":\"https:\\\/\\\/residenza-casoro.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senza categoria Archivi - Residenza Casoro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/","og_locale":"en_US","og_type":"article","og_title":"Senza categoria Archivi - Residenza Casoro","og_url":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/","og_site_name":"Residenza Casoro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/","url":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/","name":"Senza categoria Archivi - Residenza Casoro","isPartOf":{"@id":"https:\/\/residenza-casoro.ch\/en\/#website"},"breadcrumb":{"@id":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/residenza-casoro.ch\/en\/category\/senza-categoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/residenza-casoro.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Senza categoria"}]},{"@type":"WebSite","@id":"https:\/\/residenza-casoro.ch\/en\/#website","url":"https:\/\/residenza-casoro.ch\/en\/","name":"Residenza Casoro","description":"","publisher":{"@id":"https:\/\/residenza-casoro.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/residenza-casoro.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/residenza-casoro.ch\/en\/#organization","name":"Residenza Casoro","url":"https:\/\/residenza-casoro.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/residenza-casoro.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/residenza-casoro.ch\/wp-content\/uploads\/2026\/07\/Residenza-Casoro-Icon.png","contentUrl":"https:\/\/residenza-casoro.ch\/wp-content\/uploads\/2026\/07\/Residenza-Casoro-Icon.png","width":120,"height":120,"caption":"Residenza Casoro"},"image":{"@id":"https:\/\/residenza-casoro.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/residenza-casoro.ch\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/residenza-casoro.ch\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/residenza-casoro.ch\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/residenza-casoro.ch\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}